{"id":185,"date":"2025-04-26T08:04:55","date_gmt":"2025-04-26T06:04:55","guid":{"rendered":"https:\/\/mathe123.de\/?page_id=185"},"modified":"2025-04-26T08:05:32","modified_gmt":"2025-04-26T06:05:32","slug":"mathe-snack-19-49-mit-zeiten-rechnen-zeiten-umrechnen-minuten-stunden","status":"publish","type":"page","link":"https:\/\/mathe123.de\/index.php\/mathe-snack-19-49-mit-zeiten-rechnen-zeiten-umrechnen-minuten-stunden\/","title":{"rendered":"Mathe-Snack 19\/49 Mit Zeiten rechnen, Zeiten umrechnen, Minuten, Stunden"},"content":{"rendered":"\n<p>Bevor du diese Aufgabe angehst, stelle sicher:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Ich kann Zeiteinheiten &#8211; Stunden, Minuten, Sekunden &#8211; umrechnen<\/li>\n\n\n\n<li>Ich kann angeben, wieviel Minuten 1\/4 Stunde, 1\/2 Stunde oder eine 3\/4 Stunde ist<\/li>\n<\/ul>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"699\" height=\"800\" src=\"https:\/\/mathe123.de\/wp-content\/uploads\/2025\/04\/image-19.jpeg\" alt=\"\" class=\"wp-image-186\" srcset=\"https:\/\/mathe123.de\/wp-content\/uploads\/2025\/04\/image-19.jpeg 699w, https:\/\/mathe123.de\/wp-content\/uploads\/2025\/04\/image-19-262x300.jpeg 262w\" sizes=\"auto, (max-width: 699px) 100vw, 699px\" \/><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Bevor du diese Aufgabe angehst, stelle sicher:<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"categories":[],"tags":[],"class_list":["post-185","page","type-page","status-publish","hentry"],"blocksy_meta":[],"_links":{"self":[{"href":"https:\/\/mathe123.de\/index.php\/wp-json\/wp\/v2\/pages\/185","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mathe123.de\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/mathe123.de\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/mathe123.de\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/mathe123.de\/index.php\/wp-json\/wp\/v2\/comments?post=185"}],"version-history":[{"count":2,"href":"https:\/\/mathe123.de\/index.php\/wp-json\/wp\/v2\/pages\/185\/revisions"}],"predecessor-version":[{"id":188,"href":"https:\/\/mathe123.de\/index.php\/wp-json\/wp\/v2\/pages\/185\/revisions\/188"}],"wp:attachment":[{"href":"https:\/\/mathe123.de\/index.php\/wp-json\/wp\/v2\/media?parent=185"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/mathe123.de\/index.php\/wp-json\/wp\/v2\/categories?post=185"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/mathe123.de\/index.php\/wp-json\/wp\/v2\/tags?post=185"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}